{"id":35055,"date":"2024-01-25T11:41:18","date_gmt":"2024-01-25T10:41:18","guid":{"rendered":"https:\/\/thinkeat.cat\/embaras-alimentacio-saludable-a-lembaras\/"},"modified":"2024-06-18T12:41:52","modified_gmt":"2024-06-18T10:41:52","slug":"embarazo-alimentacion-saludable-al-embarazo","status":"publish","type":"post","link":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/","title":{"rendered":"Alimentaci\u00f3n saludable al embarazo"},"content":{"rendered":"<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">El pasado mas de noviembre tuvimos el placer de participar en la <strong>11.\u00aa Jornada sobre salud del embarazo en el Hospital de Barcelona con una ponencia sobre alimentaci\u00f3n saludable en el embarazo<\/strong> y un taller posterior en el cual hablamos sobre la <strong>alimentaci\u00f3n en la embarazada celiaca, vegetariana o de bajo peso<\/strong>. Si os interesa, <a href=\"https:\/\/www.hospitaldebarcelona.cat\/es\/11a-jornada-salud-del-embarazo\">aqu\u00ed teneis un v\u00eddeo con un vrece resumen de las ponencias<\/a>. Esta participaci\u00f3n nos ha llevado a escribir este blog en el cual os detallamos el m\u00e1s importante que tiene que tener en cuenta una embarazada para comer sano.<\/p>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33592 alignnone size-medium\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/45A5650-300x200.jpg\" alt=\"\" width=\"374\" height=\"250\" \/><\/p>\n<p>&nbsp;<\/p>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">El primero, y m\u00e1s importante, es que la <strong>alimentaci\u00f3n de una embarazada tiene que ser b\u00e1sicamente normal<\/strong>, es decir, <strong>saludable<\/strong> (una cosa f\u00e1cil de decir, pero que pocos realmente aplican).<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<blockquote>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Llevar una alimentaci\u00f3n saludable durante el embarazo comporta un menor riesgo de preeclampsia, diabetes gestacional y de nacimientos pret\u00e9rmino<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Es fundamental <strong>reducir el consumo de alimentos procesados, c\u00e1rnicos y derivados, az\u00facares libres, grasas\u00a0saturadas\u00a0y sal<\/strong>. Y obviamente, tenemos que asegurar una alimentaci\u00f3n rica en fruta, verdura, frutos secos, huevos, legumbres, cereales integrales y grasas saludables como el pescado azul.<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<blockquote>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Si est\u00e1s embarazada ponte en manos de un dietista-nutricionista porque te ayude a comer sano<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #a8c7af;\"><strong>Tengo que comer m\u00e1s si estoy embarazada?<\/strong><\/span><\/h3>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">En cuanto a la <strong>ENERG\u00cdA<\/strong>, la recomendaci\u00f3n es la de aumentar una media <strong>de 300\u00a0kcal\/d\u00eda\u00a0durante todo el embarazo<\/strong>. Sin embargo, la distribuci\u00f3n var\u00eda en funci\u00f3n del trimestre de la manera siguiente:<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<ul>\n<li>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\"><strong>1.\u00ba Trimestre<\/strong>: No hay necesidad de aumentar la ingesta energ\u00e9tica, pero s\u00ed que es un buen momento para ajustar los requisitos energ\u00e9ticos segundos edad, IMC y actividad f\u00edsica e iniciar el cambio de h\u00e1bitos si no se hab\u00eda hecho antes.<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\"><strong>2.\u00ba Trimestre<\/strong>: Las necesidades se ven aumentadas en 340\u00a0kcal\/d\u00eda. Qu\u00e9 quantum es esto? Aqu\u00ed ten\u00e9is 3 ejemplos del que son 340\u00a0kcal.<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-33565\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/340kcal-1-300x183.png\" alt=\"\" width=\"300\" height=\"183\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-33567\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/340kcal-2-300x178.png\" alt=\"\" width=\"300\" height=\"178\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-33569\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/340kcal-3-300x178.png\" alt=\"\" width=\"300\" height=\"178\" \/><\/p>\n<ul>\n<li>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\"><strong>3.\u00ba Trimestre<\/strong>: Las necesidades se ven aumentadas en 452\u00a0kcal\u00a0\/d\u00eda. Las 100\u00a0kcal\u00a0de diferencia con el trimestre anterior podr\u00edan aumentarse a\u00f1adiendo una de estas 3 opciones:<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-33571\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/452-kcal-1-300x192.png\" alt=\"\" width=\"300\" height=\"192\" \/>\u00a0 \u00a0\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33573\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/452-kcal-2.png\" alt=\"\" width=\"295\" height=\"206\" \/>\u00a0\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33575\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/452-kcal-3.png\" alt=\"\" width=\"291\" height=\"200\" \/><\/p>\n<blockquote>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">En resumen, una embarazada tiene que comer un poquito m\u00e1s, especialmente en el 2.\u00ba y 3.\u00ba trimestre, pero NUNCA tiene que comer por 2, ni tampoco hacer dieta, puesto que pondr\u00eda en riesgo la ingesta adecuada de nutrientes.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #a8c7af;\"><strong>Cu\u00e1nto peso tengo que ganar durante el embarazo?<\/strong><\/span><\/h3>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<p>Tanto el peso al inicio del embarazo como la ganancia de peso durante todo el proceso pueden condicionar a la salud del feto y de la mujer.<br \/>\nEn esta mesa te indicamos el peso correcto a aumentar seg\u00fan el \u00edndice de masa corporal de la mujer al inicio del embarazo:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33582 size-large\" src=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-11.39.31-1-1024x173.png\" alt=\"embarazo\" width=\"1024\" height=\"173\" \/><\/p>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Las\u00a0estimaciones asumen una tasa de aumento de peso durante el 1.\u00ba trimestre de 0,5 a 2 kg.<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<blockquote>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Durante el embarazo no se tiene que llevar una alimentaci\u00f3n restrictiva ni empezar ninguna dieta para perder peso. Del mismo modo, un aumento de peso excesivo supone un riesgo tanto para el feto y como para la mam\u00e1.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">El <strong>cambio de h\u00e1bitos alimentarios para fomentar una ganancia de peso<\/strong> adecuada durante el embarazo tendr\u00eda que iniciarse en la <strong>etapa\u00a0preconcepcional<\/strong>, puesto que se ha demostrado que la intervenci\u00f3n durante el embarazo puede ser poco efectiva.<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #a8c7af;\"><strong>Tengo que comer m\u00e1s prote\u00ednas si estoy embarazada?<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">La teor\u00eda nos dice que las necesidades de PROTE\u00cdNAS en el embarazo est\u00e1n aumentadas (0,8g\/kg\/d\u00a0vs. 1,1 g\/kg\/d). Sin embargo, sabemos que el consumo actual de prote\u00ednas est\u00e1 mucho por encima del recomendado por el cual, en la mayor\u00eda de los casos la<strong> ingesta de prote\u00ednas no tiene que aumentarse<\/strong> e incluso en algunas ocasiones tendr\u00edamos que reducir su consumo.<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Por lo tanto, la recomendaci\u00f3n general en cuanto a prote\u00ednas ir\u00e1 m\u00e1s bien dirigida al <strong>tipo de prote\u00edna<\/strong>, es decir, disminuir la prote\u00edna animal (pollo, carne, pescado) y aumentar las fuentes de prote\u00ednas vegetales (legumbres y derivados).<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<blockquote>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">El embarazo podr\u00eda ser un buen momento para vegetalitzar la alimentaci\u00f3n sustituyendo parte de la ingesta proteica animal por legumbres.<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #a8c7af;\"><strong>Tengo que vigilar con las grasas si estoy embarazada?<\/strong><\/span><\/h3>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">La respuesta es s\u00ed. Las recomendaciones de grasa en cuanto a cantidad son iguales a las de la poblaci\u00f3n en general. Sin embargo, resulta indispensable poner <strong>foco en la calidad de estas grasas, puesto que de esto depender\u00e1 el desarrollo del feto.<\/strong><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Hay que <strong>fomentar las fuentes de grasas saludables<\/strong> como el aceite de oliva virgen extra, frutos secos, semillas, aguacate, pescados azules, l\u00e1cteos y huevos, a la vez que hay que <strong>eliminar los alimentos fuente de grasas de mala calidad<\/strong> como boller\u00eda, embutidos, salsas comerciales, precocinados, snacks de bolsa, margarinas, aceite de girasol, etc.<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\"><strong>Menci\u00f3n aparte tienen los \u00e1cidos grasos omega-3.<\/strong> Durante el embarazo es esencial tener un consumo adecuado de omega-3, especialmente del tipo\u00a0DHA, puesto que interviene en la creaci\u00f3n de membranas celulares, estructuras cerebrales y en el correcto desarrollo de la retina del futuro beb\u00e9. Para cubrir requisitos se recomienda consumir:<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul>\n<li><strong>Pescado azul<\/strong> (con bajo contenido en mercurio como salm\u00f3n, boquer\u00f3n, sardina o roger), 2 veces en la semana.<\/li>\n<li>15 g de nuevos o 5 g de <strong>semillas de lino<\/strong>, diariamente.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div class=\"traductor-textarea form-group\">\n<div class=\"textarea-desti col-xs-12 col-sm-6\">\n<div class=\"form-control second-textarea\">Si tienes preguntas o quieres un asesoramiento individualizado no dudes a pedir una cita con\u00a0<a href=\"https:\/\/thinkeat.cat\/es\/\">Think&#8217;Eat<\/a> \u00a0y te ayudaremos. Y si conoces a alguien a quien le puede interesar un asesoramiento nutricional aqu\u00ed encontrar\u00e1s informaci\u00f3n sobre el nuestro\u00a0<a href=\"https:\/\/thinkeat.cat\/es\/regala-salud\/).\">PACK REGALO ESPECIAL EMBARAZO.<\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"traductor-checkbox form-group\">\n<div class=\"row\">\n<div class=\"col-sm-offset-2 col-sm-5\"><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado mas de noviembre tuvimos el placer de participar en la 11.\u00aa Jornada sobre salud del embarazo en el Hospital de Barcelona con una ponencia sobre alimentaci\u00f3n saludable en el embarazo y un taller posterior en el cual hablamos sobre la alimentaci\u00f3n en la embarazada celiaca, vegetariana o de bajo peso. Si os interesa, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[207],"tags":[],"class_list":["post-35055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-embaras-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Embar\u00e0s - Think Eat | Espai de Nutrici\u00f3 | Barcelona<\/title>\n<meta name=\"description\" content=\"La alimentaci\u00f3n durante el embarazo. Que tienes que controlar, como comer, regular prote\u00ednas, grasas... una dieta saludable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embar\u00e0s - Think Eat | Espai de Nutrici\u00f3 | Barcelona\" \/>\n<meta property=\"og:description\" content=\"La alimentaci\u00f3n durante el embarazo. Que tienes que controlar, como comer, regular prote\u00ednas, grasas... una dieta saludable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/\" \/>\n<meta property=\"og:site_name\" content=\"Think Eat | Espai de Nutrici\u00f3 | Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EspaiThinkEat\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-25T10:41:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T10:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/03\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"652\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thinkeat\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thinkeat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/\"},\"author\":{\"name\":\"Thinkeat\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#\\\/schema\\\/person\\\/efc0b95f1966ef060dad615300bf3eaf\"},\"headline\":\"Alimentaci\u00f3n saludable al embarazo\",\"datePublished\":\"2024-01-25T10:41:18+00:00\",\"dateModified\":\"2024-06-18T10:41:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/\"},\"wordCount\":935,\"publisher\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thinkeat.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg\",\"articleSection\":[\"Embar\u00e0s\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/\",\"url\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/\",\"name\":\"Embar\u00e0s - Think Eat | Espai de Nutrici\u00f3 | Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thinkeat.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg\",\"datePublished\":\"2024-01-25T10:41:18+00:00\",\"dateModified\":\"2024-06-18T10:41:52+00:00\",\"description\":\"La alimentaci\u00f3n durante el embarazo. Que tienes que controlar, como comer, regular prote\u00ednas, grasas... una dieta saludable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thinkeat.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg\",\"contentUrl\":\"https:\\\/\\\/thinkeat.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg\",\"width\":980,\"height\":652},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/embarazo-alimentacion-saludable-al-embarazo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/thinkeat.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alimentaci\u00f3n saludable al embarazo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#website\",\"url\":\"https:\\\/\\\/thinkeat.cat\\\/\",\"name\":\"Think Eat | Espai de Nutrici\u00f3 | Barcelona\",\"description\":\"Think Eat, el teu espai d&#039;assessorament i coaching nutricional dedicat a guiar-te cap a una vida plena de salut i benestar.\",\"publisher\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#organization\"},\"alternateName\":\"Think Eat\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thinkeat.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#organization\",\"name\":\"Think Eat | Espai de Nutrici\u00f3 | Barcelona\",\"alternateName\":\"Think Eat\",\"url\":\"https:\\\/\\\/thinkeat.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thinkeat.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/thinkeat.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logo-1.png\",\"width\":587,\"height\":128,\"caption\":\"Think Eat | Espai de Nutrici\u00f3 | Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EspaiThinkEat\\\/\",\"https:\\\/\\\/www.instagram.com\\\/EspaiThinkEat\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thinkeat.cat\\\/#\\\/schema\\\/person\\\/efc0b95f1966ef060dad615300bf3eaf\",\"name\":\"Thinkeat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"caption\":\"Thinkeat\"},\"sameAs\":[\"https:\\\/\\\/thinkeat.cat\"],\"url\":\"https:\\\/\\\/thinkeat.cat\\\/es\\\/author\\\/thinkeat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embar\u00e0s - Think Eat | Espai de Nutrici\u00f3 | Barcelona","description":"La alimentaci\u00f3n durante el embarazo. Que tienes que controlar, como comer, regular prote\u00ednas, grasas... una dieta saludable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/","og_locale":"es_ES","og_type":"article","og_title":"Embar\u00e0s - Think Eat | Espai de Nutrici\u00f3 | Barcelona","og_description":"La alimentaci\u00f3n durante el embarazo. Que tienes que controlar, como comer, regular prote\u00ednas, grasas... una dieta saludable.","og_url":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/","og_site_name":"Think Eat | Espai de Nutrici\u00f3 | Barcelona","article_publisher":"https:\/\/www.facebook.com\/EspaiThinkEat\/","article_published_time":"2024-01-25T10:41:18+00:00","article_modified_time":"2024-06-18T10:41:52+00:00","og_image":[{"width":980,"height":652,"url":"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/03\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg","type":"image\/jpeg"}],"author":"Thinkeat","twitter_misc":{"Escrito por":"Thinkeat","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/#article","isPartOf":{"@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/"},"author":{"name":"Thinkeat","@id":"https:\/\/thinkeat.cat\/#\/schema\/person\/efc0b95f1966ef060dad615300bf3eaf"},"headline":"Alimentaci\u00f3n saludable al embarazo","datePublished":"2024-01-25T10:41:18+00:00","dateModified":"2024-06-18T10:41:52+00:00","mainEntityOfPage":{"@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/"},"wordCount":935,"publisher":{"@id":"https:\/\/thinkeat.cat\/#organization"},"image":{"@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/#primaryimage"},"thumbnailUrl":"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/03\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg","articleSection":["Embar\u00e0s"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/","url":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/","name":"Embar\u00e0s - Think Eat | Espai de Nutrici\u00f3 | Barcelona","isPartOf":{"@id":"https:\/\/thinkeat.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/#primaryimage"},"image":{"@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/#primaryimage"},"thumbnailUrl":"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/03\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg","datePublished":"2024-01-25T10:41:18+00:00","dateModified":"2024-06-18T10:41:52+00:00","description":"La alimentaci\u00f3n durante el embarazo. Que tienes que controlar, como comer, regular prote\u00ednas, grasas... una dieta saludable.","breadcrumb":{"@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/#primaryimage","url":"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/03\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg","contentUrl":"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/03\/mujer-embarazada-manos-sosteniendo-deliciosa-ensalada-980x652-1.jpg","width":980,"height":652},{"@type":"BreadcrumbList","@id":"https:\/\/thinkeat.cat\/es\/embarazo-alimentacion-saludable-al-embarazo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/thinkeat.cat\/"},{"@type":"ListItem","position":2,"name":"Alimentaci\u00f3n saludable al embarazo"}]},{"@type":"WebSite","@id":"https:\/\/thinkeat.cat\/#website","url":"https:\/\/thinkeat.cat\/","name":"Think Eat | Espai de Nutrici\u00f3 | Barcelona","description":"Think Eat, el teu espai d&#039;assessorament i coaching nutricional dedicat a guiar-te cap a una vida plena de salut i benestar.","publisher":{"@id":"https:\/\/thinkeat.cat\/#organization"},"alternateName":"Think Eat","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thinkeat.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/thinkeat.cat\/#organization","name":"Think Eat | Espai de Nutrici\u00f3 | Barcelona","alternateName":"Think Eat","url":"https:\/\/thinkeat.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/thinkeat.cat\/#\/schema\/logo\/image\/","url":"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/05\/Logo-1.png","contentUrl":"https:\/\/thinkeat.cat\/wp-content\/uploads\/2024\/05\/Logo-1.png","width":587,"height":128,"caption":"Think Eat | Espai de Nutrici\u00f3 | Barcelona"},"image":{"@id":"https:\/\/thinkeat.cat\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EspaiThinkEat\/","https:\/\/www.instagram.com\/EspaiThinkEat"]},{"@type":"Person","@id":"https:\/\/thinkeat.cat\/#\/schema\/person\/efc0b95f1966ef060dad615300bf3eaf","name":"Thinkeat","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","caption":"Thinkeat"},"sameAs":["https:\/\/thinkeat.cat"],"url":"https:\/\/thinkeat.cat\/es\/author\/thinkeat\/"}]}},"_links":{"self":[{"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/posts\/35055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/comments?post=35055"}],"version-history":[{"count":2,"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/posts\/35055\/revisions"}],"predecessor-version":[{"id":35057,"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/posts\/35055\/revisions\/35057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/media\/34788"}],"wp:attachment":[{"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/media?parent=35055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/categories?post=35055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thinkeat.cat\/es\/wp-json\/wp\/v2\/tags?post=35055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}